{"id":20444,"date":"2026-03-24T10:19:11","date_gmt":"2026-03-24T09:19:11","guid":{"rendered":"https:\/\/www.adecose.com\/?p=20444"},"modified":"2026-04-06T16:25:39","modified_gmt":"2026-04-06T14:25:39","slug":"adecose-ingresa-en-el-consejo-consultivo-de-agers","status":"publish","type":"post","link":"https:\/\/www.adecose.com\/gl\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/","title":{"rendered":"ADECOSE ingresa en el Consejo Consultivo de AGERS"},"content":{"rendered":"<ul>\n<li><em>Borja L\u00f3pez-Chicheri, director gerente de ADECOSE, ha sido nombrado miembro del Consejo Consultivo de AGERS en representaci\u00f3n de Adecose.<\/em><\/li>\n<\/ul>\n<p>ADECOSE anuncia el nombramiento de Borja L\u00f3pez-Chicheri, director gerente de la Asociaci\u00f3n, como miembro del Consejo Consultivo de la Asociaci\u00f3n Espa\u00f1ola de Gesti\u00f3n de Riesgos y Seguros (AGERS),\u00a0organismo compuesto por profesionales de referencia del sector asegurador, como consecuencia de la invitaci\u00f3n que ha recibido la Asociaci\u00f3n a participar en su \u00f3rgano consultivo.<\/p>\n<p>Borja L\u00f3pez-Chicheri es director gerente de ADECOSE desde el a\u00f1o 2006, y adem\u00e1s es miembro del Comit\u00e9 de Directores de la Federaci\u00f3n Europea de Intermediarios de Seguros (BIPAR) desde el a\u00f1o 2008, representando los intereses de las corredur\u00edas de seguros en el \u00e1mbito europeo.<\/p>\n<p>El Consejo Consultivo de AGERS est\u00e1 integrado por profesionales procedentes de corredur\u00edas de seguros, aseguradoras, despachos de abogados, empresas y firmas especializadas. Su misi\u00f3n es asesorar y colaborar con el \u00d3rgano de Gobierno en todas aquellas actividades encaminadas al eficaz cumplimiento de los fines fundacionales, y en aquellos temas estrat\u00e9gicos que afecten al futuro de la Asociaci\u00f3n y de la profesi\u00f3n. A trav\u00e9s de encuentros peri\u00f3dicos, los profesionales que lo componen ponen en com\u00fan su conocimiento para contribuir en la toma de decisiones en el \u00e1mbito de la gesti\u00f3n de riesgos.<\/p>\n<p>\u201cEstamos encantados de formar parte del Consejo Consultivo de AGERS y confiamos en poder aportar nuestra visi\u00f3n espa\u00f1ola y europea en los temas que all\u00ed se aborden\u201d, se\u00f1ala el presidente de ADECOSE, Mart\u00edn Navaz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Borja L\u00f3pez-Chicheri, director gerente de ADECOSE, ha sido nombrado miembro del Consejo Consultivo de AGERS en representaci\u00f3n de Adecose. ADECOSE anuncia el nombramiento de Borja&#8230;<\/p>\n","protected":false},"author":197,"featured_media":20445,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[2],"tags":[284,722,724,548],"class_list":["post-20444","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","tag-adecose","tag-agers","tag-organizaciones","tag-sector-asegurador"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ADECOSE ingresa en el Consejo Consultivo de AGERS - ADECOSE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ADECOSE ingresa en el Consejo Consultivo de AGERS - ADECOSE\" \/>\n<meta property=\"og:description\" content=\"Borja L\u00f3pez-Chicheri, director gerente de ADECOSE, ha sido nombrado miembro del Consejo Consultivo de AGERS en representaci\u00f3n de Adecose. ADECOSE anuncia el nombramiento de Borja...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/\" \/>\n<meta property=\"og:site_name\" content=\"ADECOSE\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-24T09:19:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-06T14:25:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.adecose.com\/wp-content\/uploads\/2026\/03\/Borja-Lopez-Chicheri-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaci\u00f3n ADECOSE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaci\u00f3n ADECOSE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/\"},\"author\":{\"name\":\"Comunicaci\u00f3n ADECOSE\",\"@id\":\"https:\/\/www.adecose.com\/gl\/#\/schema\/person\/ff086ce55f6379e1d225a2c0dca5eeb6\"},\"headline\":\"ADECOSE ingresa en el Consejo Consultivo de AGERS\",\"datePublished\":\"2026-03-24T09:19:11+00:00\",\"dateModified\":\"2026-04-06T14:25:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/\"},\"wordCount\":275,\"publisher\":{\"@id\":\"https:\/\/www.adecose.com\/gl\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.adecose.com\/wp-content\/uploads\/2026\/03\/Borja-Lopez-Chicheri-scaled.jpg\",\"keywords\":[\"ADECOSE\",\"AGERS\",\"Organizaciones\",\"Sector Asegurador\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"gl-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/\",\"url\":\"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/\",\"name\":\"ADECOSE ingresa en el Consejo Consultivo de AGERS - ADECOSE\",\"isPartOf\":{\"@id\":\"https:\/\/www.adecose.com\/gl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.adecose.com\/wp-content\/uploads\/2026\/03\/Borja-Lopez-Chicheri-scaled.jpg\",\"datePublished\":\"2026-03-24T09:19:11+00:00\",\"dateModified\":\"2026-04-06T14:25:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/#primaryimage\",\"url\":\"https:\/\/www.adecose.com\/wp-content\/uploads\/2026\/03\/Borja-Lopez-Chicheri-scaled.jpg\",\"contentUrl\":\"https:\/\/www.adecose.com\/wp-content\/uploads\/2026\/03\/Borja-Lopez-Chicheri-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.adecose.com\/gl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ADECOSE ingresa en el Consejo Consultivo de AGERS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.adecose.com\/gl\/#website\",\"url\":\"https:\/\/www.adecose.com\/gl\/\",\"name\":\"ADECOSE\",\"description\":\"Asociaci\u00f3n Espa\u00f1ola de Corretor\u00edas de Seguros e Reaseguros\",\"publisher\":{\"@id\":\"https:\/\/www.adecose.com\/gl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.adecose.com\/gl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.adecose.com\/gl\/#organization\",\"name\":\"ADECOSE\",\"url\":\"https:\/\/www.adecose.com\/gl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\/\/www.adecose.com\/gl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.adecose.com\/wp-content\/uploads\/2020\/07\/favicon.png\",\"contentUrl\":\"https:\/\/www.adecose.com\/wp-content\/uploads\/2020\/07\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"ADECOSE\"},\"image\":{\"@id\":\"https:\/\/www.adecose.com\/gl\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.adecose.com\/gl\/#\/schema\/person\/ff086ce55f6379e1d225a2c0dca5eeb6\",\"name\":\"Comunicaci\u00f3n ADECOSE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/01cd1f9571997441bf1da6d1cc147351305f03fe8f2acf1ebbec60ebb26924ce?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/01cd1f9571997441bf1da6d1cc147351305f03fe8f2acf1ebbec60ebb26924ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/01cd1f9571997441bf1da6d1cc147351305f03fe8f2acf1ebbec60ebb26924ce?s=96&d=mm&r=g\",\"caption\":\"Comunicaci\u00f3n ADECOSE\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ADECOSE ingresa en el Consejo Consultivo de AGERS - ADECOSE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/","og_locale":"gl_ES","og_type":"article","og_title":"ADECOSE ingresa en el Consejo Consultivo de AGERS - ADECOSE","og_description":"Borja L\u00f3pez-Chicheri, director gerente de ADECOSE, ha sido nombrado miembro del Consejo Consultivo de AGERS en representaci\u00f3n de Adecose. ADECOSE anuncia el nombramiento de Borja...","og_url":"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/","og_site_name":"ADECOSE","article_published_time":"2026-03-24T09:19:11+00:00","article_modified_time":"2026-04-06T14:25:39+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.adecose.com\/wp-content\/uploads\/2026\/03\/Borja-Lopez-Chicheri-scaled.jpg","type":"image\/jpeg"}],"author":"Comunicaci\u00f3n ADECOSE","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Comunicaci\u00f3n ADECOSE","Tempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/#article","isPartOf":{"@id":"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/"},"author":{"name":"Comunicaci\u00f3n ADECOSE","@id":"https:\/\/www.adecose.com\/gl\/#\/schema\/person\/ff086ce55f6379e1d225a2c0dca5eeb6"},"headline":"ADECOSE ingresa en el Consejo Consultivo de AGERS","datePublished":"2026-03-24T09:19:11+00:00","dateModified":"2026-04-06T14:25:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/"},"wordCount":275,"publisher":{"@id":"https:\/\/www.adecose.com\/gl\/#organization"},"image":{"@id":"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.adecose.com\/wp-content\/uploads\/2026\/03\/Borja-Lopez-Chicheri-scaled.jpg","keywords":["ADECOSE","AGERS","Organizaciones","Sector Asegurador"],"articleSection":["Noticias"],"inLanguage":"gl-ES"},{"@type":"WebPage","@id":"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/","url":"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/","name":"ADECOSE ingresa en el Consejo Consultivo de AGERS - ADECOSE","isPartOf":{"@id":"https:\/\/www.adecose.com\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/#primaryimage"},"image":{"@id":"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.adecose.com\/wp-content\/uploads\/2026\/03\/Borja-Lopez-Chicheri-scaled.jpg","datePublished":"2026-03-24T09:19:11+00:00","dateModified":"2026-04-06T14:25:39+00:00","breadcrumb":{"@id":"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/#primaryimage","url":"https:\/\/www.adecose.com\/wp-content\/uploads\/2026\/03\/Borja-Lopez-Chicheri-scaled.jpg","contentUrl":"https:\/\/www.adecose.com\/wp-content\/uploads\/2026\/03\/Borja-Lopez-Chicheri-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.adecose.com\/adecose-ingresa-en-el-consejo-consultivo-de-agers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.adecose.com\/gl\/"},{"@type":"ListItem","position":2,"name":"ADECOSE ingresa en el Consejo Consultivo de AGERS"}]},{"@type":"WebSite","@id":"https:\/\/www.adecose.com\/gl\/#website","url":"https:\/\/www.adecose.com\/gl\/","name":"ADECOSE","description":"Asociaci\u00f3n Espa\u00f1ola de Corretor\u00edas de Seguros e Reaseguros","publisher":{"@id":"https:\/\/www.adecose.com\/gl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adecose.com\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/www.adecose.com\/gl\/#organization","name":"ADECOSE","url":"https:\/\/www.adecose.com\/gl\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.adecose.com\/gl\/#\/schema\/logo\/image\/","url":"https:\/\/www.adecose.com\/wp-content\/uploads\/2020\/07\/favicon.png","contentUrl":"https:\/\/www.adecose.com\/wp-content\/uploads\/2020\/07\/favicon.png","width":512,"height":512,"caption":"ADECOSE"},"image":{"@id":"https:\/\/www.adecose.com\/gl\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.adecose.com\/gl\/#\/schema\/person\/ff086ce55f6379e1d225a2c0dca5eeb6","name":"Comunicaci\u00f3n ADECOSE","image":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/01cd1f9571997441bf1da6d1cc147351305f03fe8f2acf1ebbec60ebb26924ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01cd1f9571997441bf1da6d1cc147351305f03fe8f2acf1ebbec60ebb26924ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01cd1f9571997441bf1da6d1cc147351305f03fe8f2acf1ebbec60ebb26924ce?s=96&d=mm&r=g","caption":"Comunicaci\u00f3n ADECOSE"}}]}},"_links":{"self":[{"href":"https:\/\/www.adecose.com\/gl\/wp-json\/wp\/v2\/posts\/20444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adecose.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adecose.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adecose.com\/gl\/wp-json\/wp\/v2\/users\/197"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adecose.com\/gl\/wp-json\/wp\/v2\/comments?post=20444"}],"version-history":[{"count":1,"href":"https:\/\/www.adecose.com\/gl\/wp-json\/wp\/v2\/posts\/20444\/revisions"}],"predecessor-version":[{"id":20446,"href":"https:\/\/www.adecose.com\/gl\/wp-json\/wp\/v2\/posts\/20444\/revisions\/20446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adecose.com\/gl\/wp-json\/wp\/v2\/media\/20445"}],"wp:attachment":[{"href":"https:\/\/www.adecose.com\/gl\/wp-json\/wp\/v2\/media?parent=20444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adecose.com\/gl\/wp-json\/wp\/v2\/categories?post=20444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adecose.com\/gl\/wp-json\/wp\/v2\/tags?post=20444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}