{"id":20458,"date":"2026-03-26T12:24:40","date_gmt":"2026-03-26T11:24:40","guid":{"rendered":"https:\/\/www.adecose.com\/?p=20458"},"modified":"2026-03-26T12:24:40","modified_gmt":"2026-03-26T11:24:40","slug":"wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia","status":"publish","type":"post","link":"https:\/\/www.adecose.com\/eu\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/","title":{"rendered":"WTW refuerza Embark con el lanzamiento de un Asistente Virtual impulsado por IA"},"content":{"rendered":"<p><em>Este software est\u00e1 dise\u00f1ado para comunicar, personalizar y conectar toda la propuesta de valor al empleado en un \u00fanico lugar, en cualquier momento y desde cualquier dispositivo<\/em><\/p>\n<p><strong>WTW, empresa global de consultor\u00eda y corredur\u00eda<\/strong>, ha anunciado actualizaciones en <strong>Embark<\/strong>, su<em> software<\/em> de Experiencia Empleado. Esta soluci\u00f3n ayuda a las organizaciones a incrementar el nivel de compromiso y la participaci\u00f3n en sus programas de recursos humanos, optimizar el acceso a prestaciones y simplificar la consulta de informaci\u00f3n relevante desde sus lugares de trabajo.<\/p>\n<p>Entre las novedades, destaca el <strong>lanzamiento del Asistente Virtual de Embark<\/strong>, que utiliza inteligencia artificial y est\u00e1 pensado para influir directamente en la toma de decisiones relacionadas con la experiencia de los empleados y el rendimiento de la organizaci\u00f3n.<\/p>\n<p>A diferencia de otras herramientas que responden preguntas aisladas, este asistente est\u00e1 dise\u00f1ado para conectar a las personas con informaci\u00f3n fiable y contextualizada.<\/p>\n<p>El Asistente Virtual de Embark tambi\u00e9n optimiza la experiencia de los empleados al ofrecer respuestas r\u00e1pidas, personalizadas y precisas sobre dudas relacionadas con la gesti\u00f3n de personas. Asimismo, permite a las organizaciones entender las necesidades y comportamientos de los empleados. Las funcionalidades del agente incluyen:<\/p>\n<ul>\n<li><strong>IA generativa segura para entornos empresariales:<\/strong> funciona en un entorno cerrado y controlado, utilizando exclusivamente contenido, documentos y p\u00e1ginas web que cuenten con aprobaci\u00f3n previa.<\/li>\n<li><strong>Asistencia para conversaciones personalizadas: <\/strong>los empleados pueden realizar consultas utilizando lenguaje natural y recibir respuestas adaptadas a su rol y ubicaci\u00f3n.<\/li>\n<li><strong>Referencias claras a las fuentes y su origen:<\/strong> cada respuesta est\u00e1 claramente vinculada a documentos y p\u00e1ginas originales, lo que refuerza la confianza y permite a los empleados profundizar en informaci\u00f3n verificada.<\/li>\n<li><strong>Soporte en m\u00faltiples idiomas: <\/strong>la compatibilidad del asistente con m\u00e1s de 100 idiomas permite a los empleados interactuar en su lengua, incluso cuando el contenido original est\u00e1 redactado en otro idioma.<\/li>\n<li><strong>Experiencia <\/strong><strong>alineada con la identidad corporativa<\/strong><strong>: <\/strong>las organizaciones tienen la posibilidad de adaptar elementos como la marca, el tono comunicativo, las convenciones de nomenclatura, los colores y los logotipos para reflejar su cultura y reforzar su propuesta de valor.<\/li>\n<li><strong>Controles de acceso por roles: <\/strong>las organizaciones pueden modificar los permisos seg\u00fan el rol de cada empleado, asegurando que accedan a informaci\u00f3n pertinente y manteniendo el control administrativo.<\/li>\n<li><strong>Informaci\u00f3n \u00fatil sobre la plantilla: <\/strong>las anal\u00edticas integradas ofrecen visibilidad sobre las preguntas de los empleados, los patrones de uso y los temas emergentes, ayudando a los equipos de RRHH a anticipar necesidades, mejorar las comunicaciones, optimizar resultados e identificar oportunidades.<\/li>\n<\/ul>\n<p>Este lanzamiento se enmarca en una tendencia actual: seg\u00fan el <em>Estudio de Mercado Global de Experiencia Empleado (EX)<\/em> <em>2026<\/em> de WTW, a medida que las organizaciones recurren cada vez m\u00e1s a la IA para impulsar la eficiencia, el 79% afirma que aumentar la productividad mediante su uso ser\u00e1 una prioridad durante los pr\u00f3ximos tres a\u00f1os. Este dato subraya la creciente demanda de aplicaciones pr\u00e1cticas y seguras que aporten valor real a los empleados.<\/p>\n<p><em>\u201cEl Asistente Virtual de Embark refuerza la idea de WTW de que la verdadera transformaci\u00f3n no nace solo de la tecnolog\u00eda, sino del poder de combinar inteligencia humana y herramientas inteligentes. Cuando ambos trabajan en sinton\u00eda, la informaci\u00f3n fluye y los l\u00edderes pueden tomar decisiones con impacto en resultados<\/em>\u201d, se\u00f1ala <strong>Fernanda Armada, directora de Employee Experience en WTW Espa\u00f1a. <\/strong><em>\u201cEn definitiva, es, la puerta de entrada digital a todo lo que la organizaci\u00f3n quiere comunicar y todo lo que el empleado necesita saber\u201d<\/em>, a\u00f1ade.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este software est\u00e1 dise\u00f1ado para comunicar, personalizar y conectar toda la propuesta de valor al empleado en un \u00fanico lugar, en cualquier momento y desde&#8230;<\/p>\n","protected":false},"author":197,"featured_media":19979,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[339],"tags":[284,517,406,589,342],"class_list":["post-20458","post","type-post","status-publish","format-standard","has-post-thumbnail","category-espacio-correduriasadecose","tag-adecose","tag-corredurias-de-seguros","tag-ia","tag-tecnologia","tag-wtw"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WTW refuerza Embark con el lanzamiento de un Asistente Virtual impulsado por IA - ADECOSE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/\" \/>\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WTW refuerza Embark con el lanzamiento de un Asistente Virtual impulsado por IA - ADECOSE\" \/>\n<meta property=\"og:description\" content=\"Este software est\u00e1 dise\u00f1ado para comunicar, personalizar y conectar toda la propuesta de valor al empleado en un \u00fanico lugar, en cualquier momento y desde...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/\" \/>\n<meta property=\"og:site_name\" content=\"ADECOSE\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-26T11:24:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/WTW.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaci\u00f3n ADECOSE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaci\u00f3n ADECOSE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/\"},\"author\":{\"name\":\"Comunicaci\u00f3n ADECOSE\",\"@id\":\"https:\/\/www.adecose.com\/gl\/#\/schema\/person\/ff086ce55f6379e1d225a2c0dca5eeb6\"},\"headline\":\"WTW refuerza Embark con el lanzamiento de un Asistente Virtual impulsado por IA\",\"datePublished\":\"2026-03-26T11:24:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/\"},\"wordCount\":610,\"publisher\":{\"@id\":\"https:\/\/www.adecose.com\/gl\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/WTW.jpg\",\"keywords\":[\"ADECOSE\",\"Corredur\u00edas de seguros\",\"IA\",\"Tecnolog\u00eda\",\"WTW\"],\"articleSection\":[\"Espacio #Corredur\u00edasADECOSE\"],\"inLanguage\":\"eu-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/\",\"url\":\"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/\",\"name\":\"WTW refuerza Embark con el lanzamiento de un Asistente Virtual impulsado por IA - ADECOSE\",\"isPartOf\":{\"@id\":\"https:\/\/www.adecose.com\/gl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/WTW.jpg\",\"datePublished\":\"2026-03-26T11:24:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/#primaryimage\",\"url\":\"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/WTW.jpg\",\"contentUrl\":\"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/WTW.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.adecose.com\/eu\/aseguru-eta-berraseguru-artekaritzen-espainiako-elkartea\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WTW refuerza Embark con el lanzamiento de un Asistente Virtual impulsado por IA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.adecose.com\/gl\/#website\",\"url\":\"https:\/\/www.adecose.com\/gl\/\",\"name\":\"ADECOSE\",\"description\":\"Aseguru eta Berraseguru Artekaritzen Espainiako Elkartea\",\"publisher\":{\"@id\":\"https:\/\/www.adecose.com\/gl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.adecose.com\/gl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.adecose.com\/gl\/#organization\",\"name\":\"ADECOSE\",\"url\":\"https:\/\/www.adecose.com\/gl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\/\/www.adecose.com\/gl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.adecose.com\/wp-content\/uploads\/2020\/07\/favicon.png\",\"contentUrl\":\"https:\/\/www.adecose.com\/wp-content\/uploads\/2020\/07\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"ADECOSE\"},\"image\":{\"@id\":\"https:\/\/www.adecose.com\/gl\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.adecose.com\/gl\/#\/schema\/person\/ff086ce55f6379e1d225a2c0dca5eeb6\",\"name\":\"Comunicaci\u00f3n ADECOSE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/01cd1f9571997441bf1da6d1cc147351305f03fe8f2acf1ebbec60ebb26924ce?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/01cd1f9571997441bf1da6d1cc147351305f03fe8f2acf1ebbec60ebb26924ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/01cd1f9571997441bf1da6d1cc147351305f03fe8f2acf1ebbec60ebb26924ce?s=96&d=mm&r=g\",\"caption\":\"Comunicaci\u00f3n ADECOSE\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WTW refuerza Embark con el lanzamiento de un Asistente Virtual impulsado por IA - ADECOSE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/","og_locale":"eu_ES","og_type":"article","og_title":"WTW refuerza Embark con el lanzamiento de un Asistente Virtual impulsado por IA - ADECOSE","og_description":"Este software est\u00e1 dise\u00f1ado para comunicar, personalizar y conectar toda la propuesta de valor al empleado en un \u00fanico lugar, en cualquier momento y desde...","og_url":"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/","og_site_name":"ADECOSE","article_published_time":"2026-03-26T11:24:40+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/WTW.jpg","type":"image\/jpeg"}],"author":"Comunicaci\u00f3n ADECOSE","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Comunicaci\u00f3n ADECOSE","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/#article","isPartOf":{"@id":"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/"},"author":{"name":"Comunicaci\u00f3n ADECOSE","@id":"https:\/\/www.adecose.com\/gl\/#\/schema\/person\/ff086ce55f6379e1d225a2c0dca5eeb6"},"headline":"WTW refuerza Embark con el lanzamiento de un Asistente Virtual impulsado por IA","datePublished":"2026-03-26T11:24:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/"},"wordCount":610,"publisher":{"@id":"https:\/\/www.adecose.com\/gl\/#organization"},"image":{"@id":"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/WTW.jpg","keywords":["ADECOSE","Corredur\u00edas de seguros","IA","Tecnolog\u00eda","WTW"],"articleSection":["Espacio #Corredur\u00edasADECOSE"],"inLanguage":"eu-ES"},{"@type":"WebPage","@id":"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/","url":"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/","name":"WTW refuerza Embark con el lanzamiento de un Asistente Virtual impulsado por IA - ADECOSE","isPartOf":{"@id":"https:\/\/www.adecose.com\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/#primaryimage"},"image":{"@id":"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/WTW.jpg","datePublished":"2026-03-26T11:24:40+00:00","breadcrumb":{"@id":"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/#primaryimage","url":"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/WTW.jpg","contentUrl":"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/WTW.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.adecose.com\/wtw-refuerza-embark-con-el-lanzamiento-de-un-asistente-virtual-impulsado-por-ia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.adecose.com\/eu\/aseguru-eta-berraseguru-artekaritzen-espainiako-elkartea\/"},{"@type":"ListItem","position":2,"name":"WTW refuerza Embark con el lanzamiento de un Asistente Virtual impulsado por IA"}]},{"@type":"WebSite","@id":"https:\/\/www.adecose.com\/gl\/#website","url":"https:\/\/www.adecose.com\/gl\/","name":"ADECOSE","description":"Aseguru eta Berraseguru Artekaritzen Espainiako Elkartea","publisher":{"@id":"https:\/\/www.adecose.com\/gl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adecose.com\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.adecose.com\/gl\/#organization","name":"ADECOSE","url":"https:\/\/www.adecose.com\/gl\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.adecose.com\/gl\/#\/schema\/logo\/image\/","url":"https:\/\/www.adecose.com\/wp-content\/uploads\/2020\/07\/favicon.png","contentUrl":"https:\/\/www.adecose.com\/wp-content\/uploads\/2020\/07\/favicon.png","width":512,"height":512,"caption":"ADECOSE"},"image":{"@id":"https:\/\/www.adecose.com\/gl\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.adecose.com\/gl\/#\/schema\/person\/ff086ce55f6379e1d225a2c0dca5eeb6","name":"Comunicaci\u00f3n ADECOSE","image":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/01cd1f9571997441bf1da6d1cc147351305f03fe8f2acf1ebbec60ebb26924ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01cd1f9571997441bf1da6d1cc147351305f03fe8f2acf1ebbec60ebb26924ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01cd1f9571997441bf1da6d1cc147351305f03fe8f2acf1ebbec60ebb26924ce?s=96&d=mm&r=g","caption":"Comunicaci\u00f3n ADECOSE"}}]}},"_links":{"self":[{"href":"https:\/\/www.adecose.com\/eu\/wp-json\/wp\/v2\/posts\/20458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adecose.com\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adecose.com\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adecose.com\/eu\/wp-json\/wp\/v2\/users\/197"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adecose.com\/eu\/wp-json\/wp\/v2\/comments?post=20458"}],"version-history":[{"count":1,"href":"https:\/\/www.adecose.com\/eu\/wp-json\/wp\/v2\/posts\/20458\/revisions"}],"predecessor-version":[{"id":20459,"href":"https:\/\/www.adecose.com\/eu\/wp-json\/wp\/v2\/posts\/20458\/revisions\/20459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adecose.com\/eu\/wp-json\/wp\/v2\/media\/19979"}],"wp:attachment":[{"href":"https:\/\/www.adecose.com\/eu\/wp-json\/wp\/v2\/media?parent=20458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adecose.com\/eu\/wp-json\/wp\/v2\/categories?post=20458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adecose.com\/eu\/wp-json\/wp\/v2\/tags?post=20458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}