{"id":19992,"date":"2025-11-27T08:50:14","date_gmt":"2025-11-27T07:50:14","guid":{"rendered":"https:\/\/www.adecose.com\/?p=19992"},"modified":"2025-11-27T08:50:14","modified_gmt":"2025-11-27T07:50:14","slug":"finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga","status":"publish","type":"post","link":"https:\/\/www.adecose.com\/ca\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/","title":{"rendered":"Finsa Grupo Corredur\u00eda de Seguros se incorpora al programa Alumni de la Universidad de Salamanca como Empresa Amiga"},"content":{"rendered":"<p class=\"p2\">Finsa Grupo Corredur\u00eda de Seguros ha pasado a formar parte del programa Alumni de la Universidad de Salamanca (USAL) como <b>Empresa Amiga<\/b>, tras formalizarse su incorporaci\u00f3n el pasado d\u00eda 21 en un acto celebrado en el Edificio Hist\u00f3rico de la instituci\u00f3n acad\u00e9mica. El encuentro cont\u00f3 con la presencia del rector de la Universidad de Salamanca, el presidente de Alumni y el CEO de Finsa Grupo.<\/p>\n<p class=\"p2\">El programa <b>Empresas Amigas Alumni (EAA) <\/b>tiene como finalidad impulsar el talento joven y apoyar el desarrollo empresarial de las provincias de \u00c1vila, Salamanca y Zamora. Asimismo, busca fortalecer la vinculaci\u00f3n entre empresarios y directivos relacionados con la USAL. Esta iniciativa de colaboraci\u00f3n p\u00fablico-privada re\u00fane recursos y conocimientos de diversos sectores, contribuyendo a la creaci\u00f3n de un ecosistema innovador que beneficia a estudiantes, empresas, directivos, agrupaciones empresariales, instituciones y organizaciones sin \u00e1nimo de lucro asociadas.<\/p>\n<p class=\"p2\">Joaqu\u00edn Tabernero, CEO de Finsa Grupo, expres\u00f3 su satisfacci\u00f3n por la incorporaci\u00f3n a este proyecto, que \u2014seg\u00fan destac\u00f3\u2014 permitir\u00e1 a la corredur\u00eda de seguros acceder a talento y conocimiento dentro de una comunidad formada por m\u00e1s de 35.000 alumnos, adem\u00e1s de fomentar el intercambio de experiencias con las m\u00e1s de 50 empresas e instituciones que integran la red de Empresas Amigas de Alumni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finsa Grupo Corredur\u00eda de Seguros ha pasado a formar parte del programa Alumni de la Universidad de Salamanca (USAL) como Empresa Amiga, tras formalizarse su&#8230;<\/p>\n","protected":false},"author":197,"featured_media":19993,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[339],"tags":[653,380,498],"class_list":["post-19992","post","type-post","status-publish","format-standard","has-post-thumbnail","category-espacio-correduriasadecose","tag-acuerdos-de-colaboracion","tag-formacion","tag-grupo-finsa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Finsa Grupo Corredur\u00eda de Seguros se incorpora al programa Alumni de la Universidad de Salamanca como Empresa Amiga - ADECOSE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finsa Grupo Corredur\u00eda de Seguros se incorpora al programa Alumni de la Universidad de Salamanca como Empresa Amiga - ADECOSE\" \/>\n<meta property=\"og:description\" content=\"Finsa Grupo Corredur\u00eda de Seguros ha pasado a formar parte del programa Alumni de la Universidad de Salamanca (USAL) como Empresa Amiga, tras formalizarse su...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/\" \/>\n<meta property=\"og:site_name\" content=\"ADECOSE\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-27T07:50:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/Finsa-Grupo-Correduria-de-Seguros-se-incorpora-al-programa-Alumni-de-la-Universidad-de-Salamanca-como-Empresa-Amiga.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaci\u00f3n ADECOSE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaci\u00f3n ADECOSE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/\"},\"author\":{\"name\":\"Comunicaci\u00f3n ADECOSE\",\"@id\":\"https:\/\/www.adecose.com\/gl\/#\/schema\/person\/ff086ce55f6379e1d225a2c0dca5eeb6\"},\"headline\":\"Finsa Grupo Corredur\u00eda de Seguros se incorpora al programa Alumni de la Universidad de Salamanca como Empresa Amiga\",\"datePublished\":\"2025-11-27T07:50:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/\"},\"wordCount\":238,\"publisher\":{\"@id\":\"https:\/\/www.adecose.com\/gl\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/Finsa-Grupo-Correduria-de-Seguros-se-incorpora-al-programa-Alumni-de-la-Universidad-de-Salamanca-como-Empresa-Amiga.jpg\",\"keywords\":[\"Acuerdos de colaboraci\u00f3n\",\"Formaci\u00f3n\",\"Grupo Finsa\"],\"articleSection\":[\"Espacio #Corredur\u00edasADECOSE\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/\",\"url\":\"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/\",\"name\":\"Finsa Grupo Corredur\u00eda de Seguros se incorpora al programa Alumni de la Universidad de Salamanca como Empresa Amiga - ADECOSE\",\"isPartOf\":{\"@id\":\"https:\/\/www.adecose.com\/gl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/Finsa-Grupo-Correduria-de-Seguros-se-incorpora-al-programa-Alumni-de-la-Universidad-de-Salamanca-como-Empresa-Amiga.jpg\",\"datePublished\":\"2025-11-27T07:50:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/#primaryimage\",\"url\":\"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/Finsa-Grupo-Correduria-de-Seguros-se-incorpora-al-programa-Alumni-de-la-Universidad-de-Salamanca-como-Empresa-Amiga.jpg\",\"contentUrl\":\"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/Finsa-Grupo-Correduria-de-Seguros-se-incorpora-al-programa-Alumni-de-la-Universidad-de-Salamanca-como-Empresa-Amiga.jpg\",\"width\":1600,\"height\":1067},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.adecose.com\/ca\/associacio-espanyola-de-corredories-dassegurances-i-reassegurances\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finsa Grupo Corredur\u00eda de Seguros se incorpora al programa Alumni de la Universidad de Salamanca como Empresa Amiga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.adecose.com\/gl\/#website\",\"url\":\"https:\/\/www.adecose.com\/gl\/\",\"name\":\"ADECOSE\",\"description\":\"Associaci\u00f3 Espanyola de Corredories d\u2019Assegurances i Reassegurances\",\"publisher\":{\"@id\":\"https:\/\/www.adecose.com\/gl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.adecose.com\/gl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.adecose.com\/gl\/#organization\",\"name\":\"ADECOSE\",\"url\":\"https:\/\/www.adecose.com\/gl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.adecose.com\/gl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.adecose.com\/wp-content\/uploads\/2020\/07\/favicon.png\",\"contentUrl\":\"https:\/\/www.adecose.com\/wp-content\/uploads\/2020\/07\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"ADECOSE\"},\"image\":{\"@id\":\"https:\/\/www.adecose.com\/gl\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.adecose.com\/gl\/#\/schema\/person\/ff086ce55f6379e1d225a2c0dca5eeb6\",\"name\":\"Comunicaci\u00f3n ADECOSE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/01cd1f9571997441bf1da6d1cc147351305f03fe8f2acf1ebbec60ebb26924ce?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/01cd1f9571997441bf1da6d1cc147351305f03fe8f2acf1ebbec60ebb26924ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/01cd1f9571997441bf1da6d1cc147351305f03fe8f2acf1ebbec60ebb26924ce?s=96&d=mm&r=g\",\"caption\":\"Comunicaci\u00f3n ADECOSE\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finsa Grupo Corredur\u00eda de Seguros se incorpora al programa Alumni de la Universidad de Salamanca como Empresa Amiga - ADECOSE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/","og_locale":"ca_ES","og_type":"article","og_title":"Finsa Grupo Corredur\u00eda de Seguros se incorpora al programa Alumni de la Universidad de Salamanca como Empresa Amiga - ADECOSE","og_description":"Finsa Grupo Corredur\u00eda de Seguros ha pasado a formar parte del programa Alumni de la Universidad de Salamanca (USAL) como Empresa Amiga, tras formalizarse su...","og_url":"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/","og_site_name":"ADECOSE","article_published_time":"2025-11-27T07:50:14+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/Finsa-Grupo-Correduria-de-Seguros-se-incorpora-al-programa-Alumni-de-la-Universidad-de-Salamanca-como-Empresa-Amiga.jpg","type":"image\/jpeg"}],"author":"Comunicaci\u00f3n ADECOSE","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Comunicaci\u00f3n ADECOSE","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/#article","isPartOf":{"@id":"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/"},"author":{"name":"Comunicaci\u00f3n ADECOSE","@id":"https:\/\/www.adecose.com\/gl\/#\/schema\/person\/ff086ce55f6379e1d225a2c0dca5eeb6"},"headline":"Finsa Grupo Corredur\u00eda de Seguros se incorpora al programa Alumni de la Universidad de Salamanca como Empresa Amiga","datePublished":"2025-11-27T07:50:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/"},"wordCount":238,"publisher":{"@id":"https:\/\/www.adecose.com\/gl\/#organization"},"image":{"@id":"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/#primaryimage"},"thumbnailUrl":"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/Finsa-Grupo-Correduria-de-Seguros-se-incorpora-al-programa-Alumni-de-la-Universidad-de-Salamanca-como-Empresa-Amiga.jpg","keywords":["Acuerdos de colaboraci\u00f3n","Formaci\u00f3n","Grupo Finsa"],"articleSection":["Espacio #Corredur\u00edasADECOSE"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/","url":"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/","name":"Finsa Grupo Corredur\u00eda de Seguros se incorpora al programa Alumni de la Universidad de Salamanca como Empresa Amiga - ADECOSE","isPartOf":{"@id":"https:\/\/www.adecose.com\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/#primaryimage"},"image":{"@id":"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/#primaryimage"},"thumbnailUrl":"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/Finsa-Grupo-Correduria-de-Seguros-se-incorpora-al-programa-Alumni-de-la-Universidad-de-Salamanca-como-Empresa-Amiga.jpg","datePublished":"2025-11-27T07:50:14+00:00","breadcrumb":{"@id":"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/#primaryimage","url":"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/Finsa-Grupo-Correduria-de-Seguros-se-incorpora-al-programa-Alumni-de-la-Universidad-de-Salamanca-como-Empresa-Amiga.jpg","contentUrl":"https:\/\/www.adecose.com\/wp-content\/uploads\/2025\/11\/Finsa-Grupo-Correduria-de-Seguros-se-incorpora-al-programa-Alumni-de-la-Universidad-de-Salamanca-como-Empresa-Amiga.jpg","width":1600,"height":1067},{"@type":"BreadcrumbList","@id":"https:\/\/www.adecose.com\/finsa-grupo-correduria-de-seguros-se-incorpora-al-programa-alumni-de-la-universidad-de-salamanca-como-empresa-amiga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.adecose.com\/ca\/associacio-espanyola-de-corredories-dassegurances-i-reassegurances\/"},{"@type":"ListItem","position":2,"name":"Finsa Grupo Corredur\u00eda de Seguros se incorpora al programa Alumni de la Universidad de Salamanca como Empresa Amiga"}]},{"@type":"WebSite","@id":"https:\/\/www.adecose.com\/gl\/#website","url":"https:\/\/www.adecose.com\/gl\/","name":"ADECOSE","description":"Associaci\u00f3 Espanyola de Corredories d\u2019Assegurances i Reassegurances","publisher":{"@id":"https:\/\/www.adecose.com\/gl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adecose.com\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.adecose.com\/gl\/#organization","name":"ADECOSE","url":"https:\/\/www.adecose.com\/gl\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.adecose.com\/gl\/#\/schema\/logo\/image\/","url":"https:\/\/www.adecose.com\/wp-content\/uploads\/2020\/07\/favicon.png","contentUrl":"https:\/\/www.adecose.com\/wp-content\/uploads\/2020\/07\/favicon.png","width":512,"height":512,"caption":"ADECOSE"},"image":{"@id":"https:\/\/www.adecose.com\/gl\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.adecose.com\/gl\/#\/schema\/person\/ff086ce55f6379e1d225a2c0dca5eeb6","name":"Comunicaci\u00f3n ADECOSE","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/01cd1f9571997441bf1da6d1cc147351305f03fe8f2acf1ebbec60ebb26924ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01cd1f9571997441bf1da6d1cc147351305f03fe8f2acf1ebbec60ebb26924ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01cd1f9571997441bf1da6d1cc147351305f03fe8f2acf1ebbec60ebb26924ce?s=96&d=mm&r=g","caption":"Comunicaci\u00f3n ADECOSE"}}]}},"_links":{"self":[{"href":"https:\/\/www.adecose.com\/ca\/wp-json\/wp\/v2\/posts\/19992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adecose.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adecose.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adecose.com\/ca\/wp-json\/wp\/v2\/users\/197"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adecose.com\/ca\/wp-json\/wp\/v2\/comments?post=19992"}],"version-history":[{"count":0,"href":"https:\/\/www.adecose.com\/ca\/wp-json\/wp\/v2\/posts\/19992\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adecose.com\/ca\/wp-json\/wp\/v2\/media\/19993"}],"wp:attachment":[{"href":"https:\/\/www.adecose.com\/ca\/wp-json\/wp\/v2\/media?parent=19992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adecose.com\/ca\/wp-json\/wp\/v2\/categories?post=19992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adecose.com\/ca\/wp-json\/wp\/v2\/tags?post=19992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}